{"id":13656,"date":"2023-12-18T12:48:22","date_gmt":"2023-12-18T17:48:22","guid":{"rendered":"https:\/\/mcc2022.wpengine.com\/?page_id=13656"},"modified":"2026-06-01T08:44:03","modified_gmt":"2026-06-01T12:44:03","slug":"resultats","status":"publish","type":"page","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/","title":{"rendered":"R\u00e9sultats"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13656\" class=\"elementor elementor-13656 elementor-13240\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8bd706a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bd706a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-607b60a\" data-id=\"607b60a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f44312 elementor-widget elementor-widget-mwpagemenu\" data-id=\"7f44312\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mwpagemenu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"collapsible-menu\"><div class=\"icon-container\"><div class=\"icon\"><p>Menu de section<\/p><i class=\"menu-icon fas fa-chevron-down\"><\/i><\/div><\/div><div class=\"menu-content\"><div class=\"mw-pagemenu\"><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/\"><span class=\"link-title\">Aper\u00e7u<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/admissibilite-et-demande\/\"><span class=\"link-title\">Admissibilit\u00e9 et demande<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/planification\/\"><span class=\"link-title\">Planification<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/jour-de-lexamen\/\"><span class=\"link-title\">Jour de l'examen<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"active\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/\"><span class=\"link-title\">R\u00e9sultats<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/retrait\/\"><span class=\"link-title\">Retrait<\/span><div class=\"block-border\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78dccca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78dccca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-633b96a\" data-id=\"633b96a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8581d96 elementor-widget elementor-widget-text-editor\" data-id=\"8581d96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Recevoir vos r\u00e9sultats de l\u2019examen li\u00e9 \u00e0 la PDT<\/h2><p>Le Conseil m\u00e9dical du Canada (CMC) dispose d\u2019un syst\u00e8me de notation tr\u00e8s rigoureux et d\u2019un solide processus d\u2019assurance de la qualit\u00e9 visant \u00e0 s\u2019assurer que le rendement de chaque candidat est \u00e9valu\u00e9 correctement. Avant d\u2019\u00eatre communiqu\u00e9s, les r\u00e9sultats finals sont v\u00e9rifi\u00e9s \u00e0 plusieurs reprises pour en garantir l\u2019exactitude.<\/p><p>Les r\u00e9sultats seront disponibles pour les programmes d\u2019\u00e9valuation de la capacit\u00e9 \u00e0 exercer (ECE) <strong>5<\/strong> <strong>semaines<\/strong> apr\u00e8s la date de l\u2019examen. Votre lettre de r\u00e9sultats sera \u00e9galement t\u00e9l\u00e9charg\u00e9e dans votre compte inscriptionmed.ca.<\/p><p>Vous recevrez un avis par courriel et un message dans votre compte inscriptionmed.ca indiquant que vous pouvez v\u00e9rifier votre r\u00e9sultat dans votre compte.<\/p><p>L\u2019examen li\u00e9 \u00e0 la PDT ne fournit actuellement qu\u2019un r\u00e9sultat de r\u00e9ussite ou d\u2019\u00e9chec. Aucune note n&rsquo;est communiqu\u00e9e aux candidats ou aux programmes d\u2019ECE pour l\u2019instant.<\/p><p><span style=\"color: #2e717c;\"><i class=\"fas fa-chevron-right\" aria-hidden=\"true\"><\/i>\u00a0 <a href=\"\/fr\/examens-et-evaluations\/evaluation-de-la-capacite-a-exercer\/\">En savoir plus sur les programmes d&rsquo;ECE<\/a><\/span><\/p><p>Afin de pr\u00e9venir toute fraude, ainsi que pour prot\u00e9ger la confidentialit\u00e9, vos r\u00e9sultats de l\u2019examen li\u00e9 \u00e0 la PDT ne seront accessibles que dans votre compte inscriptionmed.ca et ne seront jamais communiqu\u00e9s ni par t\u00e9l\u00e9phone ni par courriel.<\/p><p><strong>Remarque : <\/strong>Le CMC analyse la qualit\u00e9 de l\u2019\u00e9valuation post-examen et rajuste la structure de notation pour un examen donn\u00e9 lorsqu\u2019il est \u00e9tabli, \u00e0 la discr\u00e9tion exclusive et absolue du CMC, que ladite analyse est n\u00e9cessaire ou appropri\u00e9e en vue d\u2019assurer la validit\u00e9 ou l\u2019int\u00e9grit\u00e9 de l\u2019examen. Les d\u00e9cisions prises par le CMC dans de tels cas sont d\u00e9finitives et ne peuvent faire l\u2019objet d\u2019un appel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b64177 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b64177\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-379c057\" data-id=\"379c057\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a7f168 elementor-widget elementor-widget-text-editor\" data-id=\"2a7f168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Validit\u00e9 des r\u00e9sultats<\/h2><p>Seuls les r\u00e9sultats les plus r\u00e9cents seront valides, quels que soient les r\u00e9sultats ant\u00e9rieurs (r\u00e9ussite ou \u00e9chec).<\/p><p>Les r\u00e9sultats sont valides pour tous les programmes d\u2019ECE provinciaux qui exigent l\u2019examen li\u00e9 \u00e0 la PDT, peu importe la province o\u00f9 vous avez pass\u00e9 l\u2019examen li\u00e9 \u00e0 la PDT.\u00a0<\/p><p>\u00a0\u00c0 compter de septembre 2026, la p\u00e9riode de validit\u00e9 appliqu\u00e9e par le CMC \u00e0 un r\u00e9sultat de r\u00e9ussite \u00e0 l\u2019examen li\u00e9 \u00e0 la PDT sera \u00e9limin\u00e9e. Les programmes d\u2019ECE pourront choisir d\u2019\u00e9tablir des exigences en mati\u00e8re de r\u00e9cence selon leurs propres crit\u00e8res d\u2019\u00e9valuation; ces exigences ne sont plus d\u00e9termin\u00e9es par le CMC.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e8fc66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e8fc66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a3b89c\" data-id=\"8a3b89c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45534cc elementor-widget elementor-widget-text-editor\" data-id=\"45534cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Comprendre votre r\u00e9sultat de l\u2019examen li\u00e9 \u00e0 la PDT<\/h2><h3>R\u00e9sultat de r\u00e9ussite ou d\u2019\u00e9chec\u00a0<\/h3><p>Le r\u00e9sultat final de l\u2019examen li\u00e9 \u00e0 la PDT (par ex. r\u00e9ussite ou \u00e9chec) d\u00e9pend uniquement de la position de votre note globale par rapport \u00e0 la note de passage. Une note globale \u00e9gale ou sup\u00e9rieure \u00e0 la note de passage est une r\u00e9ussite, et une note globale inf\u00e9rieure \u00e0 la note de passage est un \u00e9chec, ce qui signifie que vous r\u00e9ussirez si vous atteignez ou d\u00e9passez la note de passage, quel que soit le rendement des autres candidats.<\/p><p>L\u2019examen li\u00e9 \u00e0 la PDT ne fournit actuellement qu\u2019un r\u00e9sultat de r\u00e9ussite ou d\u2019\u00e9chec. Aucune note n&rsquo;est communiqu\u00e9e aux candidats ou aux programmes d\u2019ECE pour l\u2019instant.<\/p><p>Le Comit\u00e9 de supervision des examens (CSE) est compos\u00e9 de m\u00e9decins et d\u2019enseignants en m\u00e9decine de partout au pays et est responsable d\u2019attribuer les r\u00e9sultats de r\u00e9ussite ou d\u2019\u00e9chec aux candidats qui ont pass\u00e9 l\u2019examen li\u00e9 \u00e0 la PDT.<\/p><h3>Comment l\u2019examen est not\u00e9\u00a0<\/h3><p>L\u2019examen li\u00e9 \u00e0 la PDT est not\u00e9 automatiquement selon une cl\u00e9 de correction pour chaque question. La note globale d\u2019un candidat correspond \u00e0 la somme de son rendement sur l\u2019ensemble des questions. Afin d\u2019assurer l\u2019\u00e9quit\u00e9 au fil du temps, les notes sont plac\u00e9es sur une \u00e9chelle commune \u00e0 l\u2019aide d\u2019un processus statistique appel\u00e9 \u00ab mise en \u00e9quation \u00bb, qui relie chaque nouveau formulaire d\u2019examen \u00e0 l\u2019\u00e9chelle de r\u00e9f\u00e9rence qui a \u00e9t\u00e9 \u00e9tablie en f\u00e9vrier 2026.<\/p><p>La notation est effectu\u00e9e au moyen de deux processus ind\u00e9pendants, mais parall\u00e8les, \u00e0 l\u2019aide du logiciel d\u2019analyse statistique SAS<sup>MD<\/sup> (Statistical Analysis System). Les r\u00e9sultats des deux processus sont compar\u00e9s et doivent correspondre avant d\u2019\u00eatre communiqu\u00e9s aux programmes d\u2019ECE et aux candidats \u00e0 l\u2019examen.<\/p><h3>Examen \u00e0 interpr\u00e9tation crit\u00e9ri\u00e9e\u00a0<\/h3><p>L\u2019examen li\u00e9 \u00e0 la PDT est un examen \u00e0 interpr\u00e9tation crit\u00e9ri\u00e9e, ce qui signifie qu\u2019un r\u00e9sultat de r\u00e9ussite ou d\u2019\u00e9chec est d\u00e9termin\u00e9 en comparant votre rendement individuel \u00e0 un standard de rendement, et non au rendement des autres candidats.<\/p><p>Lorsqu\u2019un examen est fond\u00e9 sur des crit\u00e8res, la seule chose qui compte vraiment est votre rendement par rapport \u00e0 la note de passage. Pour l\u2019examen li\u00e9 \u00e0 la PDT, la r\u00e9ussite est consid\u00e9r\u00e9e comme une \u00ab comp\u00e9tence acceptable \u00bb. Un candidat ayant r\u00e9ussi l\u2019examen qui a obtenu quelques points de plus n\u2019a pas n\u00e9cessairement une comp\u00e9tence plus \u00ab acceptable \u00bb qu\u2019une personne ayant r\u00e9ussi l\u2019examen avec quelques points de moins, ou vice versa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b20e3d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b20e3d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee4f57e\" data-id=\"ee4f57e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caec91f elementor-widget elementor-widget-text-editor\" data-id=\"caec91f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Comment la note de passage de l\u2019examen li\u00e9 \u00e0 la PDT est d\u00e9termin\u00e9e<\/h2><p>\u00c0 intervalle de quelques ann\u00e9es, le CMC r\u00e9unit un panel de m\u00e9decins canadiens pour d\u00e9finir un niveau acceptable de rendement et \u00e9tablir la note de passage de l\u2019examen li\u00e9 \u00e0 la PDT, au moyen d\u2019un exercice d\u2019\u00e9tablissement du seuil de r\u00e9ussite.<\/p><p>En f\u00e9vrier 2026, le CMC a men\u00e9 un rigoureux exercice d\u2019\u00e9tablissement du seuil de r\u00e9ussite avec un panel de 20 m\u00e9decins de famille de tout le Canada. Au cours de cet exercice, le panel de m\u00e9decins s\u2019est appuy\u00e9 sur les meilleures m\u00e9thodes afin de recommander une note de passage qui a \u00e9t\u00e9 pr\u00e9sent\u00e9e au CSE pour \u00eatre examin\u00e9e et approuv\u00e9e. La nouvelle note de passage approuv\u00e9e par le CSE sera appliqu\u00e9e \u00e0 la session d\u2019examen de janvier 2026 et aux sessions ult\u00e9rieures.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b12137 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b12137\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21e9a1c\" data-id=\"21e9a1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2551cb3 elementor-widget elementor-widget-heading\" data-id=\"2551cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Continuer la lecture...<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d72d1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d72d1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dea54e1\" data-id=\"dea54e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0fa040 elementor-widget elementor-widget-mwnavigator\" data-id=\"a0fa040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mwnavigator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mw-navigator\"><div class=\"link-block\"><a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/jour-de-lexamen\/\"><span class=\"link-title\">Jour de l'examen<\/span><span class=\"indicator\">Section pr\u00e9c\u00e9dente<\/span><\/a><\/div><div class=\"link-block\"><a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/retrait\/\"><span class=\"link-title\">Retrait<\/span><span class=\"indicator\">Section suivante<\/span><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Section menu Aper\u00e7uAdmissibilit\u00e9 et demandePlanificationJour de l&rsquo;examenR\u00e9sultatsRetrait Recevoir vos r\u00e9sultats de l\u2019examen li\u00e9 \u00e0 la PDT Le Conseil m\u00e9dical du Canada (CMC) dispose d\u2019un syst\u00e8me de notation tr\u00e8s rigoureux et d\u2019un solide processus d\u2019assurance de la qualit\u00e9 visant \u00e0 s\u2019assurer que le rendement de chaque candidat est \u00e9valu\u00e9 correctement. Avant d\u2019\u00eatre communiqu\u00e9s, les r\u00e9sultats finals [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"parent":13617,"menu_order":21,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"3897","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-13656","page","type-page","status-publish","hentry"],"acf":{"inherit_intro_image":true,"page_intro_text":"Quand vous pouvez vous attendre \u00e0 recevoir vos r\u00e9sultats de l\u2019examen li\u00e9 \u00e0 la PDT, et comment les comprendre. \r\n"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le Conseil m\u00e9dical du Canada |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"R\u00e9sultats | Le Conseil m\u00e9dical du Canada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-18T17:48:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-01T12:44:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"R\u00e9sultats | Le Conseil m\u00e9dical du Canada\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/resultats\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/#listItem\",\"name\":\"Examens et \\u00e9valuations\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/#listItem\",\"position\":2,\"name\":\"Examens et \\u00e9valuations\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/#listItem\",\"name\":\"Examen li\\u00e9 \\u00e0 la PDT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/#listItem\",\"position\":3,\"name\":\"Examen li\\u00e9 \\u00e0 la PDT\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/resultats\\\/#listItem\",\"name\":\"R\\u00e9sultats\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/#listItem\",\"name\":\"Examens et \\u00e9valuations\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/resultats\\\/#listItem\",\"position\":4,\"name\":\"R\\u00e9sultats\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/#listItem\",\"name\":\"Examen li\\u00e9 \\u00e0 la PDT\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#organization\",\"name\":\"Le Conseil m\\u00e9dical du Canada\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/resultats\\\/#webpage\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/resultats\\\/\",\"name\":\"R\\u00e9sultats | Le Conseil m\\u00e9dical du Canada\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/examen-lie-a-la-pdt\\\/resultats\\\/#breadcrumblist\"},\"datePublished\":\"2023-12-18T12:48:22-05:00\",\"dateModified\":\"2026-06-01T08:44:03-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\",\"name\":\"Medical Council of Canada\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"R\u00e9sultats | Le Conseil m\u00e9dical du Canada","description":"","canonical_url":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/mcc.ca\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/#listItem","name":"Examens et \u00e9valuations"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/#listItem","position":2,"name":"Examens et \u00e9valuations","item":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/#listItem","name":"Examen li\u00e9 \u00e0 la PDT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/#listItem","position":3,"name":"Examen li\u00e9 \u00e0 la PDT","item":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/#listItem","name":"R\u00e9sultats"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/#listItem","name":"Examens et \u00e9valuations"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/#listItem","position":4,"name":"R\u00e9sultats","previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/#listItem","name":"Examen li\u00e9 \u00e0 la PDT"}}]},{"@type":"Organization","@id":"https:\/\/mcc.ca\/fr\/#organization","name":"Le Conseil m\u00e9dical du Canada","url":"https:\/\/mcc.ca\/fr\/"},{"@type":"WebPage","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/#webpage","url":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/","name":"R\u00e9sultats | Le Conseil m\u00e9dical du Canada","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/mcc.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/#breadcrumblist"},"datePublished":"2023-12-18T12:48:22-05:00","dateModified":"2026-06-01T08:44:03-04:00"},{"@type":"WebSite","@id":"https:\/\/mcc.ca\/fr\/#website","url":"https:\/\/mcc.ca\/fr\/","name":"Medical Council of Canada","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/mcc.ca\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le Conseil m\u00e9dical du Canada |","og:type":"article","og:title":"R\u00e9sultats | Le Conseil m\u00e9dical du Canada","og:url":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/","og:image":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png","og:image:secure_url":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png","og:image:width":500,"og:image:height":224,"article:published_time":"2023-12-18T17:48:22+00:00","article:modified_time":"2026-06-01T12:44:03+00:00","twitter:card":"summary","twitter:title":"R\u00e9sultats | Le Conseil m\u00e9dical du Canada","twitter:image":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png"},"aioseo_meta_data":{"post_id":"13656","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-01-04 18:15:02","updated":"2026-06-01 12:44:24","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/\" title=\"Examens et \u00e9valuations\">Examens et \u00e9valuations<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/\" title=\"Examen li\u00e9 \u00e0 la PDT\">Examen li\u00e9 \u00e0 la PDT<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tR\u00e9sultats\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mcc.ca\/fr\/"},{"label":"Examens et \u00e9valuations","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/"},{"label":"Examen li\u00e9 \u00e0 la PDT","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/"},{"label":"R\u00e9sultats","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/examen-lie-a-la-pdt\/resultats\/"}],"_links":{"self":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/comments?post=13656"}],"version-history":[{"count":5,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13656\/revisions"}],"predecessor-version":[{"id":31638,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13656\/revisions\/31638"}],"up":[{"embeddable":true,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13617"}],"wp:attachment":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/media?parent=13656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}