{"id":13290,"date":"2023-11-27T15:43:05","date_gmt":"2023-11-27T20:43:05","guid":{"rendered":"https:\/\/mcc2022.wpengine.com\/?page_id=13290"},"modified":"2026-06-23T11:43:42","modified_gmt":"2026-06-23T15:43:42","slug":"le-jour-de-lexamen","status":"publish","type":"page","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/","title":{"rendered":"Jour de l&rsquo;examen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13290\" class=\"elementor elementor-13290 elementor-12430\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49eff40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49eff40\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8bbc1f\" data-id=\"c8bbc1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f256b30 elementor-widget elementor-widget-mwpagemenu\" data-id=\"f256b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mwpagemenu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"collapsible-menu\"><div class=\"icon-container\"><div class=\"icon\"><p>Menu de section<\/p><i class=\"menu-icon fas fa-chevron-down\"><\/i><\/div><\/div><div class=\"menu-content\"><div class=\"mw-pagemenu\"><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/\"><span class=\"link-title\">Aper\u00e7u<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/admissibilite-et-demande\/\"><span class=\"link-title\">Admissibilit\u00e9 et demande<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/planification\/\"><span class=\"link-title\">Planification<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"active\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/\"><span class=\"link-title\">Jour de l'examen<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/resultats\/\"><span class=\"link-title\">R\u00e9sultats<\/span><div class=\"block-border\"><\/div><\/a><\/div><div class=\"link-block\"><a class=\"inactive\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/retrait\/\"><span class=\"link-title\">Retrait\u00a0<\/span><div class=\"block-border\"><\/div><\/a><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8cbbedf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8cbbedf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb86469\" data-id=\"fb86469\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f681e4f elementor-widget elementor-widget-text-editor\" data-id=\"f681e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Proc\u00e9dures d\u2019arriv\u00e9e et d\u2019enregistrement\u00a0<\/h2><p>Consultez les directives et les d\u00e9tails relatifs pour votre examen en personne, notamment des renseignements concernant les articles personnels dont vous avez besoin, ce que vous pouvez apporter et ce que vous ne pouvez pas avoir avec vous pendant l\u2019examen.\u00a0<\/p><h3>Je passe mon examen\u202f:<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d889e5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d889e5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b94fd57\" data-id=\"b94fd57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2536640 elementor-widget elementor-widget-image\" data-id=\"2536640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/fr\/examens-et-evaluations\/enregistrement-avec-proproctor\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-remote-proctoring-1024x683.jpg\" class=\"attachment-large size-large wp-image-12435\" alt=\"Decorative image of someone at a desktop computer typing onto the keyboard\" srcset=\"https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-remote-proctoring-1024x683.jpg 1024w, https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-remote-proctoring-300x200.jpg 300w, https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-remote-proctoring-768x512.jpg 768w, https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-remote-proctoring-1536x1024.jpg 1536w, https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-remote-proctoring-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d59668a listing-heading elementor-widget elementor-widget-heading\" data-id=\"d59668a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/fr\/examens-et-evaluations\/enregistrement-avec-proproctor\/\">Par voie de surveillance \u00e0 distance    <i><\/i><\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-39b3850\" data-id=\"39b3850\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a15b8c3 elementor-widget elementor-widget-image\" data-id=\"a15b8c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/fr\/examens-et-evaluations\/enregistrement-au-centre-dexamen-de-prometric\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"401\" src=\"https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-exam-center-.jpg\" class=\"attachment-large size-large wp-image-12433\" alt=\"Decorative image of the work stations at a Prometric Site.\" srcset=\"https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-exam-center-.jpg 600w, https:\/\/mcc.ca\/wp-content\/uploads\/Exam-day-exam-center--300x201.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa763d listing-heading elementor-widget elementor-widget-heading\" data-id=\"2aa763d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/fr\/examens-et-evaluations\/enregistrement-au-centre-dexamen-de-prometric\/\">Dans un centre d\u2019examen    <i><\/i><\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24486fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24486fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-714d04a\" data-id=\"714d04a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e5d6ca elementor-widget elementor-widget-text-editor\" data-id=\"0e5d6ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Dur\u00e9e de l\u2019EACMC<\/h2><p>Chaque rendez-vous d\u2019examen dure 6,5 heures, ce qui comprend\u202f:<\/p><ol><li>L\u2019ouverture de votre session d\u2019examen et le contr\u00f4le de s\u00e9curit\u00e9;<br \/>Remarque: Vous effectuerez votre inscription avant de d\u00e9buter votre rendez-vous d&rsquo;examen.<\/li><li>Un tutoriel sur le fonctionnement de l\u2019application d\u2019examen et une vid\u00e9o sur les mesures de s\u00e9curit\u00e9 d\u2019examen;<\/li><li>Deux heures et quarante minutes pour effectuer la premi\u00e8re section de <a href=\"\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/questions-a-choix-multiple\/\">questions \u00e0 choix multiple (QCM)<\/a>;<\/li><li>Une pause facultative de 45\u202fminutes;<\/li><li>Deux heures et quarante minutes pour effectuer la deuxi\u00e8me section de QCM;<\/li><li>Un sondage facultatif \u00e0 la fin de l&rsquo;examen.<\/li><\/ol><p>Si un accommodement d\u2019examen vous donnant du temps suppl\u00e9mentaire pour passer l\u2019examen vous a \u00e9t\u00e9 pr\u00e9alablement accord\u00e9, ce temps sera ajout\u00e9 aux deux sections de QCM.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f7d948 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f7d948\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd6e132\" data-id=\"bd6e132\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2036b60 elementor-widget elementor-widget-text-editor\" data-id=\"2036b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Prise de notes pendant l\u2019EACMC<\/h2><p>Au centre d&rsquo;examen, vous pourrez prendre des notes pendant l\u2019examen \u00e0 l\u2019aide d&rsquo;un tableau effa\u00e7able \u00e0 sec.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb250c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb250c6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da05467\" data-id=\"da05467\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e8958 elementor-widget elementor-widget-text-editor\" data-id=\"59e8958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Gestion du temps pendant l\u2019examen<\/h2><h3>Suivi de la progression et du temps<\/h3><p>La barre de progression permet de suivre les r\u00e9ponses aux questions pendant toute la dur\u00e9e de l\u2019examen. Elle est cumulative d\u2019une section \u00e0 l\u2019autre et ne se r\u00e9initialise pas apr\u00e8s chaque section. Par exemple, si vous r\u00e9pondez \u00e0 toutes les questions, votre barre de progression devrait indiquer environ 50 % \u00e0 la fin de la premi\u00e8re section de QCM et 100 % \u00e0 la fin de la deuxi\u00e8me section. La barre de progression n&rsquo;inclut pas les questions du sondage.<\/p><p>L\u2019application d\u2019examen vous indiquera \u00e9galement le temps qu\u2019il vous reste. L\u2019horloge de l\u2019application d\u2019examen ne peut pas \u00eatre arr\u00eat\u00e9e une fois que vous commencez l\u2019examen. Vous recevrez des avertissements lorsque vous approcherez de 30 minutes, 15 minutes et 5 minutes avant la fin de chaque section d\u2019examen. Votre examen sera termin\u00e9 lorsque vous soumettrez l\u2019examen ou lorsque le temps d\u2019examen sera \u00e9coul\u00e9, selon la premi\u00e8re \u00e9ventualit\u00e9.<\/p><p>Si un d\u00e9lai se produit entre les questions ou pendant le chargement des \u00e9l\u00e9ments, la minuterie de l\u2019examen s\u2019arr\u00eate et ne red\u00e9marre que lorsqu\u2019un \u00e9l\u00e9ment est enti\u00e8rement rendu. Aucun temps d\u2019examen n\u2019est perdu.<\/p><p>Lorsque l\u2019examen sera fini, un avis confirmant que vous avez termin\u00e9 l\u2019EACMC<span style=\"background-color: var( --e-global-color-bf7e5bf );\">\u00a0s\u2019affichera sur l\u2019\u00e9cran de l\u2019ordinateur. L\u2019avis d\u2019ach\u00e8vement vous sera \u00e9galement envoy\u00e9 par courriel une fois que vous aurez termin\u00e9 votre examen. Cet avis ne comprendra pas votre note totale ni votre r\u00e9sultat final.<\/span><\/p><h3>QCM | Deux sections de 2 heures et 40 minutes<\/h3><p>Dans chaque section de QCM, vous disposez de 2 heures et 40 minutes pour r\u00e9pondre \u00e0 115 QCM. En moyenne, vous devez pr\u00e9voir 1 minute et 23 secondes par question pour r\u00e9pondre \u00e0 toutes les questions. Vous pouvez marquer des questions et y revenir \u00e0 tout moment pendant la section.<\/p><p>Une fois que vous aurez quitt\u00e9 une section de QCM, vous ne pourrez plus y revenir. Toute question laiss\u00e9e sans r\u00e9ponse sera consid\u00e9r\u00e9e comme incorrecte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59bca1e elementor-widget elementor-widget-spacer\" data-id=\"59bca1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47f2442 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47f2442\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98c19ce\" data-id=\"98c19ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ff005d elementor-widget elementor-widget-text-editor\" data-id=\"1ff005d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Pauses\u00a0<\/h2><h3>Pause facultative\u00a0<\/h3><p>Il n\u2019y a qu\u2019une seule pause facultative de 45 minutes qui commencera une fois que vous aurez termin\u00e9 et soumis la premi\u00e8re section de QCM. Vous pouvez prendre une pause de moins de 45 minutes si vous souhaitez commencer la deuxi\u00e8me section de QCM plus t\u00f4t en cliquant sur <strong>Reprendre le test<\/strong>, par contre, cela ne vous donne pas plus de temps pour l\u2019examen. Si vous n\u2019avez pas mis fin \u00e0 la pause facultative plus t\u00f4t, la minuterie pour la deuxi\u00e8me section d\u00e9marrera automatiquement apr\u00e8s que les 45\u202fminutes se sont \u00e9coul\u00e9es.<\/p><p>Vous pouvez \u00e9galement choisir de mettre fin \u00e0 cette pause \u00e0 tout moment en cliquant sur <strong>Reprendre le test<\/strong>. Toute p\u00e9riode inutilis\u00e9e de la pause facultative sera perdue.\u202f<\/p><p>Pour des raisons de s\u00e9curit\u00e9, vous devez quitter la salle d\u2019examen pendant la pause facultative de 45 minutes. Lors de cette pause, vous pouvez avoir acc\u00e8s \u00e0 de la nourriture, un t\u00e9l\u00e9phone cellulaire, des boissons ou des m\u00e9dicaments. Veillez \u00e0 pr\u00e9voir le temps n\u00e9cessaire pour effectuer le processus de s\u00e9curit\u00e9 et d\u2019enregistrement lorsque vous retournez \u00e0 l\u2019examen.<\/p><h3>Pauses non pr\u00e9vues<\/h3><p>Vous pouvez \u00e9galement prendre des pauses non pr\u00e9vues pendant l\u2019examen pour vous procurer de la nourriture, des boissons autres que de l&rsquo;eau ou des m\u00e9dicaments. Vous devez g\u00e9rer vos pauses non pr\u00e9vues dans les limites du temps allou\u00e9 \u00e0 l\u2019examen, car la minuterie de l\u2019examen continuera de calculer le temps restant. Vous devrez \u00e9galement vous soumettre aux proc\u00e9dures de contr\u00f4le de s\u00e9curit\u00e9 \u00e0 votre retour.<\/p><p>Pour prendre une pause non pr\u00e9vue\u202f:<\/p><ol><li>Informez un membre du personnel de Prometric comme indiqu\u00e9 au d\u00e9but de l\u2019examen.<\/li><li>Quittez la salle d\u2019examen. La minuterie de l\u2019examen continuera de calculer le temps restant pendant votre pause.<\/li><li>Effectuez le contr\u00f4le de s\u00e9curit\u00e9 de routine et le processus d\u2019enregistrement pour revenir \u00e0 l\u2019examen. Cette op\u00e9ration devrait prendre entre 3 et 5 minutes.<\/li><\/ol><p>Aucun contact ext\u00e9rieur n\u2019est autoris\u00e9 pendant toute la dur\u00e9e de la s\u00e9ance d\u2019examen, y compris pendant la pause facultative et les pauses non pr\u00e9vues.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afeff78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afeff78\" data-element_type=\"section\" data-e-type=\"section\" id=\"exam-incidents\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01aa038\" data-id=\"01aa038\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fb3fb6 elementor-widget elementor-widget-text-editor\" data-id=\"0fb3fb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Que faire en cas d\u2019incident le jour de l\u2019examen<\/h2><h3>Difficult\u00e9s techniques<\/h3><p>Le personnel de Prometric est disponible sur place pour offrir du soutien en cas de probl\u00e8me technique ou autre. Si vous \u00e9prouvez des difficult\u00e9s techniques pendant l\u2019examen, veuillez informer un membre du personnel de Prometric imm\u00e9diatement, car il pourrait \u00eatre en mesure de vous aider.<\/p><h3>Signalement d\u2019incidents le jour de l\u2019examen<\/h3><p>Le CMC reconna\u00eet que, dans certains cas, les candidats peuvent \u00eatre confront\u00e9s \u00e0 des incidents le jour de l\u2019examen (irr\u00e9gularit\u00e9s de proc\u00e9dure ou circonstances att\u00e9nuantes, par exemple, la maladie) qui peuvent avoir une incidence sur leur rendement le jour de l\u2019examen.<\/p><p>Si vous choisissez de commencer l\u2019examen, cela comptera comme une tentative m\u00eame si vous ne pouvez pas le terminer, et vos droits d\u2019inscription pourraient ne pas vous \u00eatre rembours\u00e9s.<\/p><p>Il est important d<strong>\u2019informer imm\u00e9diatement le personnel du centre<\/strong> de tout incident survenu le jour de l\u2019examen.<\/p><p>En plus d\u2019aviser le personnel le jour de l\u2019examen, <strong>vous devez signaler au CMC<\/strong> tout incident survenu le jour de l\u2019examen (irr\u00e9gularit\u00e9s de proc\u00e9dure et circonstances att\u00e9nuantes) par le biais de de votre compte inscriptionmed.ca<strong> dans les 7 jours suivant l\u2019examen<\/strong>.<\/p><p>Le CMC n\u2019enqu\u00eatera pas sur les incidents survenus le jour de l\u2019examen qui ont \u00e9t\u00e9 signal\u00e9s plus de 7 jours apr\u00e8s la date de votre rendez-vous d\u2019examen. Les candidats n\u2019ayant pas signal\u00e9 d\u2019incidents dans ce d\u00e9lai de 7\u00a0jours ne pourront pas faire une demande de r\u00e9\u00e9valuation lorsque les r\u00e9sultats auront \u00e9t\u00e9 communiqu\u00e9s. Les r\u00e9ponses au sondage ne font pas l\u2019objet de rapport d\u2019incidents, le sondage n\u2019\u00e9tant con\u00e7u que pour permettre aux candidats de fournir une r\u00e9troaction g\u00e9n\u00e9rale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e186641 elementor-widget elementor-widget-button\" data-id=\"e186641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/examens-et-evaluations\/demandes-relatives-aux-examens\/reevaluation-et-demande-dappel\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9\u00e9valuation et demande d\u2019appel <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8893ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8893ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efb7cf6\" data-id=\"efb7cf6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cb49eb elementor-widget elementor-widget-text-editor\" data-id=\"6cb49eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Conduite et comportement<\/h2><p>Vous serez surveill\u00e9 par le personnel de Prometric tout au long de l\u2019examen. Prometric enregistrera sous format vid\u00e9o (avec ou sans le son) la surveillance de l\u2019examen du CMC qu\u2019il offre conform\u00e9ment aux modalit\u00e9s de l\u2019EACMC que vous avez accept\u00e9es au moment de la demande. Aux centres d\u2019examen o\u00f9 des cam\u00e9ras sont install\u00e9es, des avis seront affich\u00e9s pour vous informer que la session est enregistr\u00e9e. Tous les renseignements personnels recueillis dans ces enregistrements seront trait\u00e9s conform\u00e9ment \u00e0 la <a href=\"\/fr\/politique-sur-la-protection-des-renseignements-personnels\/\">Politique sur la protection des renseignements personnels du CMC<\/a>.<\/p><p>Il est interdit de parler \u00e0 quelqu\u2019un d\u2019autre que le personnel de Prometric pendant votre rendez-vous d\u2019examen, et l\u2019acc\u00e8s \u00e0 tout appareil de communication ou de transmission, y compris les t\u00e9l\u00e9phones ou les tablettes, est interdit pendant l\u2019examen.<\/p><p>Vous devez compl\u00e9ter l\u2019EACMC tout seul; il est interdit de fournir ou de recevoir de l\u2019aide pour compl\u00e9ter l\u2019EACMC, car cela est consid\u00e9r\u00e9 comme un manquement aux modalit\u00e9s de l\u2019EACMC. Si vous semblez donner ou recevoir des renseignements pendant l\u2019examen, les membres du personnel de Prometric responsables de l\u2019examen peuvent mettre imm\u00e9diatement fin \u00e0 votre examen. Les membres du personnel de Prometric doivent faire un rapport complet de tous ces \u00e9v\u00e9nements au CMC.<\/p><p>Tous les documents de l\u2019EACMC, y compris le contenu et les questions de l\u2019EACMC, sont prot\u00e9g\u00e9s par des droits d\u2019auteur et doivent demeurer confidentiels. Vous \u00eates autoris\u00e9 \u00e0 utiliser le mat\u00e9riel de l\u2019EACMC uniquement pour passer l\u2019examen. Vous ne devez pas diffuser, reproduire, divulguer ou r\u00e9v\u00e9ler le mat\u00e9riel et le contenu de l\u2019examen, partiellement ou dans son int\u00e9gralit\u00e9, en tout temps et de quelque fa\u00e7on que ce soit, m\u00eame apr\u00e8s la fin de l\u2019examen. La comparaison du contenu de l\u2019examen et des th\u00e8mes des questions avec vos coll\u00e8gues, la divulgation du contenu avec les futurs candidats \u00e0 l\u2019examen et la publication du contenu en ligne sont consid\u00e9r\u00e9s comme des atteintes \u00e0 la confidentialit\u00e9.<\/p><p>Tout manquement aux modalit\u00e9s de l\u2019EACMC sera consid\u00e9r\u00e9 comme un comportement r\u00e9pr\u00e9hensible pour lequel le CMC pourra prendre des mesures appropri\u00e9es, conform\u00e9ment aux modalit\u00e9s de l\u2019EACMC que vous avez accept\u00e9es au moment de la demande.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-044ee10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"044ee10\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0364094\" data-id=\"0364094\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6ad5a6 elementor-widget elementor-widget-heading\" data-id=\"c6ad5a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">En savoir plus...<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd82f96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd82f96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2883db5\" data-id=\"2883db5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cfb13f elementor-widget elementor-widget-mwnavigator\" data-id=\"6cfb13f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mwnavigator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mw-navigator\"><div class=\"link-block\"><a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/planification\/\"><span class=\"link-title\">Planification<\/span><span class=\"indicator\">Section pr\u00e9c\u00e9dente<\/span><\/a><\/div><div class=\"link-block\"><a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/resultats\/\"><span class=\"link-title\">R\u00e9sultats<\/span><span class=\"indicator\">Section suivante<\/span><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Section menu Aper\u00e7u Proc\u00e9dures d\u2019arriv\u00e9e et d\u2019enregistrement\u00a0 Consultez les directives et les d\u00e9tails relatifs pour votre examen en personne, notamment des renseignements concernant les articles personnels dont vous avez besoin, ce que vous pouvez apporter et ce que vous ne pouvez pas avoir avec vous pendant l\u2019examen.\u00a0 Je passe mon examen\u202f: Par voie de surveillance [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"parent":10219,"menu_order":66,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"3897","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-13290","page","type-page","status-publish","hentry"],"acf":{"inherit_intro_image":true,"page_intro_text":"\u00c0 quoi s\u2019attendre le jour de l\u2019examen d\u2019aptitude du Conseil m\u00e9dical du Canada (EACMC), (anciennement EACMC, partie I).\r\n"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le Conseil m\u00e9dical du Canada |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jour de l\u2019examen | Le Conseil m\u00e9dical du Canada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-27T20:43:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-23T15:43:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jour de l\u2019examen | Le Conseil m\u00e9dical du Canada\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/le-jour-de-lexamen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/#listItem\",\"name\":\"Examens et \\u00e9valuations\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/#listItem\",\"position\":2,\"name\":\"Examens et \\u00e9valuations\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/#listItem\",\"name\":\"EACMC\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/#listItem\",\"position\":3,\"name\":\"EACMC\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/le-jour-de-lexamen\\\/#listItem\",\"name\":\"Jour de l&rsquo;examen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/#listItem\",\"name\":\"Examens et \\u00e9valuations\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/le-jour-de-lexamen\\\/#listItem\",\"position\":4,\"name\":\"Jour de l&rsquo;examen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/#listItem\",\"name\":\"EACMC\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#organization\",\"name\":\"Le Conseil m\\u00e9dical du Canada\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/le-jour-de-lexamen\\\/#webpage\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/le-jour-de-lexamen\\\/\",\"name\":\"Jour de l\\u2019examen | Le Conseil m\\u00e9dical du Canada\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/examens-et-evaluations\\\/eacmc\\\/le-jour-de-lexamen\\\/#breadcrumblist\"},\"datePublished\":\"2023-11-27T15:43:05-05:00\",\"dateModified\":\"2026-06-23T11:43:42-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\",\"name\":\"Medical Council of Canada\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jour de l\u2019examen | Le Conseil m\u00e9dical du Canada","description":"","canonical_url":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/mcc.ca\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/#listItem","name":"Examens et \u00e9valuations"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/#listItem","position":2,"name":"Examens et \u00e9valuations","item":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/#listItem","name":"EACMC"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/#listItem","position":3,"name":"EACMC","item":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/#listItem","name":"Jour de l&rsquo;examen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/#listItem","name":"Examens et \u00e9valuations"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/#listItem","position":4,"name":"Jour de l&rsquo;examen","previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/#listItem","name":"EACMC"}}]},{"@type":"Organization","@id":"https:\/\/mcc.ca\/fr\/#organization","name":"Le Conseil m\u00e9dical du Canada","url":"https:\/\/mcc.ca\/fr\/"},{"@type":"WebPage","@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/#webpage","url":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/","name":"Jour de l\u2019examen | Le Conseil m\u00e9dical du Canada","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/mcc.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/#breadcrumblist"},"datePublished":"2023-11-27T15:43:05-05:00","dateModified":"2026-06-23T11:43:42-04:00"},{"@type":"WebSite","@id":"https:\/\/mcc.ca\/fr\/#website","url":"https:\/\/mcc.ca\/fr\/","name":"Medical Council of Canada","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/mcc.ca\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le Conseil m\u00e9dical du Canada |","og:type":"article","og:title":"Jour de l\u2019examen | Le Conseil m\u00e9dical du Canada","og:url":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/","og:image":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png","og:image:secure_url":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png","og:image:width":500,"og:image:height":224,"article:published_time":"2023-11-27T20:43:05+00:00","article:modified_time":"2026-06-23T15:43:42+00:00","twitter:card":"summary","twitter:title":"Jour de l\u2019examen | Le Conseil m\u00e9dical du Canada","twitter:image":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png"},"aioseo_meta_data":{"post_id":"13290","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-12-19 16:14:49","updated":"2026-06-23 15:44:42","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/\" title=\"Examens et \u00e9valuations\">Examens et \u00e9valuations<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/\" title=\"EACMC\">EACMC<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJour de l\u2019examen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mcc.ca\/fr\/"},{"label":"Examens et \u00e9valuations","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/"},{"label":"EACMC","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/"},{"label":"Jour de l&rsquo;examen","link":"https:\/\/mcc.ca\/fr\/examens-et-evaluations\/eacmc\/le-jour-de-lexamen\/"}],"_links":{"self":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/comments?post=13290"}],"version-history":[{"count":5,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13290\/revisions"}],"predecessor-version":[{"id":32519,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/13290\/revisions\/32519"}],"up":[{"embeddable":true,"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/pages\/10219"}],"wp:attachment":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/media?parent=13290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}