{"id":9000,"date":"2026-03-31T08:00:00","date_gmt":"2026-03-31T12:00:00","guid":{"rendered":"https:\/\/mcc2022.wpengine.com\/?post_type=objectives&#038;p=9000"},"modified":"2026-03-31T08:01:51","modified_gmt":"2026-03-31T12:01:51","slug":"masse-cervicale-goitre-maladie-thyroidienne","status":"publish","type":"objectives","link":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/","title":{"rendered":"Masses cervicales et pathologies thyro\u00efdiennes"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Explication<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que la plupart des masses cervicales soient b\u00e9nignes, il est essentiel de les distinguer de celles qui sont malignes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9tiologie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">(liste non exhaustive)<\/p>\n\n\n\n<ol style=\"list-style-type:ordered\" class=\"wp-block-list\">\n<li>Masses b\u00e9nignes\n<ol style=\"list-style-type:lower-alpha\" class=\"wp-block-list\">\n<li>Causes cong\u00e9nitales (p. ex. kyste du canal thyr\u00e9oglosse)<\/li>\n\n\n\n<li>Causes inflammatoires (p. ex. ad\u00e9nopathie r\u00e9actionnelle)<\/li>\n\n\n\n<li>N\u00e9oplasies (p. ex. lipomes)<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li>Masses malignes\n<ol style=\"list-style-type:lower-alpha\" class=\"wp-block-list\">\n<li>Nodules thyro\u00efdiens<\/li>\n\n\n\n<li>Cancers non thyro\u00efdiens de la t\u00eate et du cou<\/li>\n\n\n\n<li>Lymphomes<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Objectifs principaux<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cas d\u2019un patient pr\u00e9sentant une masse cervicale, le candidat devra en diagnostiquer la cause, la gravit\u00e9 et les complications, et mettre en place un plan de prise en charge appropri\u00e9. Il devra accorder une attention particuli\u00e8re \u00e0 l\u2019exclusion d\u2019un \u00e9ventuel cancer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Objectifs sp\u00e9cifiques<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cas d\u2019un patient pr\u00e9sentant une masse cervicale, le candidat devra<\/p>\n\n\n\n<ol style=\"list-style-type:ordered\" class=\"wp-block-list\">\n<li>\u00e9num\u00e9rer et interpr\u00e9ter les constatations cliniques cruciales, notamment celles d\u00e9coulant :\n<ol style=\"list-style-type:lower-alpha\" class=\"wp-block-list\">\n<li>d\u2019une anamn\u00e8se et d\u2019un examen physique appropri\u00e9s, effectu\u00e9s en accordant une attention particuli\u00e8re :\n<ol style=\"list-style-type:lower-roman\" class=\"wp-block-list\">\n<li>aux facteurs de risque de cancer (p. ex. tabagisme, trouble de l\u2019usage de l\u2019alcool);<\/li>\n\n\n\n<li>\u00e0 l\u2019\u00e9volution dans le temps;<\/li>\n\n\n\n<li>\u00e0 la pr\u00e9sence de douleurs, de sympt\u00f4mes li\u00e9s \u00e0 la d\u00e9glutition ou de sympt\u00f4mes syst\u00e9miques;<\/li>\n\n\n\n<li>aux signes et sympt\u00f4mes de dysfonctionnement de la thyro\u00efde;<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li>\u00e9num\u00e9rer les examens essentiels, s\u2019il y a lieu, et en interpr\u00e9ter les r\u00e9sultats, notamment :\n<ol style=\"list-style-type:lower-alpha\" class=\"wp-block-list\">\n<li>les tests de fonction thyro\u00efdienne;<\/li>\n\n\n\n<li>les examens d\u2019imagerie diagnostique;<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li>\u00e9tablir un plan efficace de prise en charge initiale, notamment :\n<ol style=\"list-style-type:lower-alpha\" class=\"wp-block-list\">\n<li>rassurer le patient et faire un suivi appropri\u00e9 en cas de l\u00e9sions pr\u00e9sum\u00e9es b\u00e9nignes;<\/li>\n\n\n\n<li>prescrire les m\u00e9dicaments appropri\u00e9s (p. ex. suppl\u00e9ment thyro\u00efdien, antibiotiques);<\/li>\n\n\n\n<li>orienter le patient vers des soins sp\u00e9cialis\u00e9s (p. ex. aspiration \u00e0 l\u2019aiguille fine, biopsie au trocart, biopsie ouverte), s\u2019il y a lieu.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Explication Bien que la plupart des masses cervicales soient b\u00e9nignes, il est essentiel de les distinguer de celles qui sont malignes. \u00c9tiologie (liste non exhaustive) Objectifs principaux Dans le cas d\u2019un patient pr\u00e9sentant une masse cervicale, le candidat devra en diagnostiquer la cause, la gravit\u00e9 et les complications, et mettre en place un plan de [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":241,"template":"","format":"standard","class_list":["post-9000","objectives","type-objectives","status-publish","format-standard","hentry"],"acf":{"legacy_id":"63","version":"mars 2026"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le Conseil m\u00e9dical du Canada |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Masses cervicales et pathologies thyro\u00efdiennes | Le Conseil m\u00e9dical du Canada\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-31T12:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-31T12:01:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Masses cervicales et pathologies thyro\u00efdiennes | Le Conseil m\u00e9dical du Canada\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/masse-cervicale-goitre-maladie-thyroidienne\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/#listItem\",\"name\":\"Objectives\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/#listItem\",\"position\":2,\"name\":\"Objectives\",\"item\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/masse-cervicale-goitre-maladie-thyroidienne\\\/#listItem\",\"name\":\"Masses cervicales et pathologies thyro\\u00efdiennes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/masse-cervicale-goitre-maladie-thyroidienne\\\/#listItem\",\"position\":3,\"name\":\"Masses cervicales et pathologies thyro\\u00efdiennes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/#listItem\",\"name\":\"Objectives\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#organization\",\"name\":\"Le Conseil m\\u00e9dical du Canada\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/masse-cervicale-goitre-maladie-thyroidienne\\\/#webpage\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/masse-cervicale-goitre-maladie-thyroidienne\\\/\",\"name\":\"Masses cervicales et pathologies thyro\\u00efdiennes | Le Conseil m\\u00e9dical du Canada\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/objectifs\\\/expert-medical\\\/masse-cervicale-goitre-maladie-thyroidienne\\\/#breadcrumblist\"},\"datePublished\":\"2026-03-31T08:00:00-04:00\",\"dateModified\":\"2026-03-31T08:01:51-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/\",\"name\":\"Medical Council of Canada\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcc.ca\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Masses cervicales et pathologies thyro\u00efdiennes | Le Conseil m\u00e9dical du Canada","description":"","canonical_url":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/mcc.ca\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/#listItem","name":"Objectives"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/#listItem","position":2,"name":"Objectives","item":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/#listItem","name":"Masses cervicales et pathologies thyro\u00efdiennes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/#listItem","position":3,"name":"Masses cervicales et pathologies thyro\u00efdiennes","previousItem":{"@type":"ListItem","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/#listItem","name":"Objectives"}}]},{"@type":"Organization","@id":"https:\/\/mcc.ca\/fr\/#organization","name":"Le Conseil m\u00e9dical du Canada","url":"https:\/\/mcc.ca\/fr\/"},{"@type":"WebPage","@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/#webpage","url":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/","name":"Masses cervicales et pathologies thyro\u00efdiennes | Le Conseil m\u00e9dical du Canada","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/mcc.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/#breadcrumblist"},"datePublished":"2026-03-31T08:00:00-04:00","dateModified":"2026-03-31T08:01:51-04:00"},{"@type":"WebSite","@id":"https:\/\/mcc.ca\/fr\/#website","url":"https:\/\/mcc.ca\/fr\/","name":"Medical Council of Canada","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/mcc.ca\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le Conseil m\u00e9dical du Canada |","og:type":"article","og:title":"Masses cervicales et pathologies thyro\u00efdiennes | Le Conseil m\u00e9dical du Canada","og:url":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/","og:image":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png","og:image:secure_url":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png","og:image:width":500,"og:image:height":224,"article:published_time":"2026-03-31T12:00:00+00:00","article:modified_time":"2026-03-31T12:01:51+00:00","twitter:card":"summary","twitter:title":"Masses cervicales et pathologies thyro\u00efdiennes | Le Conseil m\u00e9dical du Canada","twitter:image":"https:\/\/mcc.ca\/wp-content\/uploads\/MCC-logo.png"},"aioseo_meta_data":{"post_id":"9000","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-07-26 17:04:50","updated":"2026-03-31 12:08:15","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/\" title=\"Objectives\">Objectives<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMasses cervicales et pathologies thyro\u00efdiennes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mcc.ca\/fr\/"},{"label":"Objectives","link":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/"},{"label":"Masses cervicales et pathologies thyro\u00efdiennes","link":"https:\/\/mcc.ca\/fr\/objectifs\/expert-medical\/masse-cervicale-goitre-maladie-thyroidienne\/"}],"_links":{"self":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/objectives\/9000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/objectives"}],"about":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/types\/objectives"}],"wp:attachment":[{"href":"https:\/\/mcc.ca\/fr\/wp-json\/wp\/v2\/media?parent=9000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}